
{"id":28,"count":3,"description":"","link":"https:\/\/www.boessiocompeticoes.com.br\/ftruck\/tag\/promovendo-avancos-em-tecnologia\/","name":"promovendo avan\u00e7os em tecnologia","slug":"promovendo-avancos-em-tecnologia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.boessiocompeticoes.com.br\/ftruck\/wp-json\/wp\/v2\/tags\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.boessiocompeticoes.com.br\/ftruck\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.boessiocompeticoes.com.br\/ftruck\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.boessiocompeticoes.com.br\/ftruck\/wp-json\/wp\/v2\/posts?tags=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}